{"id":84,"date":"2017-10-06T00:00:00","date_gmt":"2017-10-05T22:00:00","guid":{"rendered":"https:\/\/www.sindacatocronisti.it\/wordpress\/2017\/10\/06\/diffamazione-25-anni-di-riforme-abortite\/"},"modified":"2017-10-06T00:00:00","modified_gmt":"2017-10-05T22:00:00","slug":"diffamazione-25-anni-di-riforme-abortite","status":"publish","type":"post","link":"https:\/\/www.sindacatocronisti.it\/wordpress\/2017\/10\/06\/diffamazione-25-anni-di-riforme-abortite\/","title":{"rendered":"Diffamazione, 25 anni di riforme abortite"},"content":{"rendered":"<div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Read Time:<\/span>3 Minute, 21 Second                <\/div>\n\n            <\/div><p>Parlamentari e politici sono e saranno in campagna elettorale nei prossimi mesi e non hanno tempo da perdere per legiferare.&nbsp;<br \/> Se rischiano di rimanere lettera morta in questo finale di XVII legislatura quasi un centinaio di ddl paralizzati in mezzo al guado fra Camera e Senato, e alcuni clamorosi quanto scomodi come quelli sui vitalizi degli onorevoli, sullo \u201cius soli\u201d, sul processo penale (dentro la censura sulle intercettazioni), sul testamento biologico e sulla propaganda fascista, il record dell\u2019eterna incompiuta spetta alla riforma della diffamazione a mezzo stampa. Da 3 anni esatti marcia a passo di gambero in commissione giustizia al Senato, tradendo un paralizzante vizio liberticida, che, in 25 anni di tentativi e di legislature bruciate una dopo l\u2019altra, ha impedito di cambiare le regole della legge sulla stampa del 1948 che, bench\u00e9 vecchie e marcite, appaiono meno pericolose delle tante velleit\u00e0 di aggiustamenti rincorse finora. Dopo gli annosi balletti fra i due rami del Parlamento, l\u2019ultima versione (varata alla Camera nel giugno 2015) rivela come sia cervellotico per il potere trovare un compromesso fra il bastone e la carota sulla pelle dei cronisti, fra la voglia di bavagli e il diritto del cittadino a conoscere i fatti senza veli ed ad essere informato compiutamente.&nbsp;<br \/> Dietro lo specchietto per le allodole dell\u2019abolizione del carcere (peraltro sempre stato un bau bau) spuntano spinosi lacci e laccioli, maximulte salate e ricattatorie, e rettifiche a monologhi. Una prospettiva che Rodot\u00e0 giudic\u00f2 senza mezzi termini \u201cpericolosa non solo per l\u2019informazione, ma per la stessa democrazia\u201d. Un giudizio calzante verso legislatori che ignorano o fingono di ignorare la potenza intimidatoria delle querele temerarie e pretestuose con richieste esorbitanti di risarcimento danni, cercando di ridurre a livelli risibili (1.000\/10.000 euro) l\u2019indennizzo al giornalista trascinato in cause infondate (il 90% del totale) a fronteggiare pretese milionarie.&nbsp;<br \/> Nel corso di questi primi due decenni del 2000, la tela di Penelope della riforma si \u00e8 fatta e disfatta in Parlamento innumerevoli volte innanzitutto per la discordia parlamentare, ma anche per la sempre pi\u00f9 accanita reazione dei giornalisti con alla testa i cronisti, i primi ad allarmare la categoria e il sindacato. Ma un ruolo determinante l\u2019hanno avuto la Corte europea e la Cassazione emanando documenti e sentenze inequivocabili sulla libert\u00e0 di stampa e sul diritto di cronaca. Cos\u00ec si bocciarono, si arenarono, naufragarono e si dispersero negli andirivieni fra i rami parlamentari progetti pseudo riformisti: alla Camera febbraio 2001; Anedda maggio 2002 lungo la strada; gi\u00f9 al Senato ottobre 2004; oppure finiti nel nulla o mai discussi come nel dicembre 2008, nel febbraio 2009, nel luglio e nell\u2019ottobre 2012 senza contare i tanti ddl presentati e messi in frigorifero.&nbsp;<br \/> Un pluriennale dibattito tra i cronisti ha fornito nel tempo tre indicazioni di base per una riforma non marchiata dal potere: la rettifica commentata per scongiurare le bugie grossolane; il risarcimento equo ai giornalisti per le querele temerarie (prendendo spunto dalla lite temeraria gi\u00e0 prevista dai codici); privacy quasi zero per amministratori pubblici di ogni livello per ragioni sociali, etiche e di trasparenza politica.&nbsp;<br \/> Senza una riforma a regola d\u2019arte, continueranno, comunque, a restare in piedi norme oppressive ispirate al codice fascista Rocco e che strangolano il lavoro dei giornalisti. Prove inquietanti sono fornite da \u201cOssigeno per l\u2019informazione\u201d con il suo Osservatorio sui giornalisti minacciati in Italia. Nel 2015, la legge sulla diffamazione, che il Parlamento non corregge, ha leso e colpito duro il diritto di cronaca: 103 anni di galera ai giornalisti; 5.125 querele infondate (quasi il 90%); 911 citazioni per risarcimento; 45,6 milioni di euro di richieste di danni; 54 milioni si euro di spese legale; 2 anni e mezzo per essere prosciolti; 6 anni per la sentenza di primo grado. Ed ecco cosa accade, secondo \u201cOssigeno per l\u2019informazione\u201d, ai cronisti senza peli sulla lingua: 30 vivono sotto scorta; 3.000 hanno denunciato minacce; 30.000 hanno subito intimidazioni (il 40% con querele pretestuose).&nbsp; (06\/10\/2017)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parlamentari e politici sono e saranno in campagna elettorale nei prossimi mesi e non hanno tempo da perdere per legiferare.&nbsp; Se rischiano di rimanere lettera morta in questo finale di XVII legislatura quasi un centinaio di ddl paralizzati in mezzo al guado fra Camera e Senato, e alcuni clamorosi quanto scomodi come quelli sui vitalizi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-84","post","type-post","status-publish","format-standard","hentry","category-archivioarticoliprecedenti"],"_links":{"self":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/comments?post=84"}],"version-history":[{"count":0,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/84\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/media?parent=84"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/categories?post=84"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/tags?post=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}