{"id":597,"date":"2015-08-24T18:05:30","date_gmt":"2015-08-24T16:05:30","guid":{"rendered":"https:\/\/www.sindacatocronisti.it\/wordpress\/2020\/08\/24\/niente-carcere-solo-multe\/"},"modified":"2020-08-24T22:40:33","modified_gmt":"2020-08-24T20:40:33","slug":"niente-carcere-solo-multe","status":"publish","type":"post","link":"https:\/\/www.sindacatocronisti.it\/wordpress\/2015\/08\/24\/niente-carcere-solo-multe\/","title":{"rendered":"Niente carcere, solo multe"},"content":{"rendered":"<div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Read Time:<\/span>2 Minute, 4 Second                <\/div>\n\n            <\/div><p>Passa alla Camera la \u201cnuova diffamazione\u201d Il carcere per i giornalisti in caso di diffamazione \u00e8 stato cancellato: saranno possibili solo pene pecuniarie. Con multe che vanno da 5 a 10mila euro o, in caso di fatto \u00abconsapevolmente falso\u00bb da 10 a 50mila euro. \u00c8 nel testo della proposta di legge approvata ieri dalla Camera dei deputati, e che ora passa al Senato. Viene imposto per\u00f2 l\u2019obbligo di rettifica &#8211; su richiesta dell\u2019offeso &#8211; senza possibilit\u00e0 di commento a meno che non siano penalmente rilevanti oppure \u00abinequivocabilmente false\u00bb. E la rettifica tempestiva verr\u00e0 considerata dal giudice come causa di non punibilit\u00e0. Viene poi stemperata la responsabilit\u00e0 del direttore per omesso controllo, che in fatti recenti ha raggiunto &#8211; come denunciato dal Sindacato cronisti romani &#8211; casi paradossali, come quando un direttore \u00e8 stato condannato a otto mesi di prigione per non aver controllato il testo di un necrologio. Ora l\u2019omesso controllo pu\u00f2 essere imputato al direttore o al suo vice facenti funzioni se vi \u00e8 un nesso di casualit\u00e0 tra omesso controllo e diffamazione. La pena &#8211; sempre pecuniaria &#8211; in questo caso \u00e8 comunque ridotta di un terzo rispetto al giornalista che ha redatto il testo ritenuto diffamatorio. Il direttore potr\u00e0 delegare &#8211; per iscritto &#8211; un altro giornalista alla vigilanza dei servizi, e questi si trover\u00e0 responsabile &#8211; anche penalmente &#8211; dell\u2019attivit\u00e0 di controllo. Ancora: in caso di condanna, sar\u00e0 obbligatoria la pubblicazione della sentenza. I giornalisti autori del servizio ritenuto diffamatorio, in caso di recidiva, potranno essere interdetti dalla professione per un tempo da uno a sei mesi. In caso di richiesta di rettifica, il direttore sar\u00e0 obbligato a informare l\u2019autore del testo o servizio diffamatorio, perch\u00e9 questi sar\u00e0 nominato obbligatoriamente nella replica di tutela dell\u2019offeso. Se la sanzione penale prevede un massimo di 50mila euro nei casi pi\u00f9 gravi, l\u2019azione civile &#8211; che si potr\u00e0 intentare entro due anni &#8211; potr\u00e0 comportare una richiesta di risarcimento pi\u00f9 elevata, ma &#8211; per la proposta di legge che ora passer\u00e0 al Senato &#8211; questa dovr\u00e0 essere commisurata anche alla diffusione e importanza della testata, oltre che naturalmente dalla gravit\u00e0 dell\u2019offesa. Novit\u00e0 sulla questione \u2013 pi\u00f9 volte rimarcata dal Sindacato cronisti romani \u2013 delle \u201ccause temerarie\u201d, le cause cio\u00e8 con richieste esorbitanti previste ad arte per intimidire i giornalisti. Nel testo della proposta di legge, in caso di cause temerarie sar\u00e0 prevista un\u2019ammenda fino a diecimila euro a carico del querelante (se causa penale) o un rimborso commisurato alla somma richiesta in caso di causa civile senza fondamento.<\/p>\n<p>SCR<\/p>\n<p>25\/06\/15<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Passa alla Camera la \u201cnuova diffamazione\u201d Il carcere per i giornalisti in caso di diffamazione \u00e8 stato cancellato: saranno possibili solo pene pecuniarie. Con multe che vanno da 5 a 10mila euro o, in caso di fatto \u00abconsapevolmente falso\u00bb da 10 a 50mila euro. \u00c8 nel testo della proposta di legge approvata ieri dalla Camera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-597","post","type-post","status-publish","format-standard","hentry","category-archivioarticoliprecedenti"],"_links":{"self":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/comments?post=597"}],"version-history":[{"count":1,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/597\/revisions"}],"predecessor-version":[{"id":625,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/597\/revisions\/625"}],"wp:attachment":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/media?parent=597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/categories?post=597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/tags?post=597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}