{"id":593,"date":"2015-08-24T18:05:30","date_gmt":"2015-08-24T16:05:30","guid":{"rendered":"https:\/\/www.sindacatocronisti.it\/wordpress\/2020\/08\/24\/allarme-pensioni-quello-che-si-rischia-sui-tagli-dellinpgi-abbiamo-diritto-a-sapere\/"},"modified":"2020-08-24T22:56:19","modified_gmt":"2020-08-24T20:56:19","slug":"allarme-pensioni-quello-che-si-rischia-sui-tagli-dellinpgi-abbiamo-diritto-a-sapere","status":"publish","type":"post","link":"https:\/\/www.sindacatocronisti.it\/wordpress\/2015\/08\/24\/allarme-pensioni-quello-che-si-rischia-sui-tagli-dellinpgi-abbiamo-diritto-a-sapere\/","title":{"rendered":"Allarme pensioni: quello che si rischia Sui tagli dell\u2019Inpgi abbiamo diritto a sapere"},"content":{"rendered":"<div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Read Time:<\/span>7 Minute, 13 Second                <\/div>\n\n            <\/div><p><strong>di Romano Bartoloni <\/strong><br \/>\n(segretario del SCR e presidente del Gruppo romano giornalisti pensionati)<\/p>\n<p>Anche se all\u2019Inpgi restano abbottonati contro ogni buona regola di trasparenza, di rispetto dei diritti\/doveri dei soci e di coinvolgimento e corresponsabilit? dell\u2019intera categoria (nell\u2019Inpgi1 15mila i contrattualizzati a tempo indeterminato e 8mila i pensionati), sembra che si profilino inevitabili sacrifici per rimettere in sesto i conti. Di questa inquietante prospettiva, peraltro dietro l\u2019angolo nonostante i contorni siano ancora indefiniti, si ? discusso nel corso dell\u2019ultima riunione del Direttivo del Gruppo romano giornalisti pensionati, al quale ha partecipato il fiduciario romano Inpgi, Ignazio Ingrao, mettendoci in guardia con franchezza, della quale siamo grati, su quello che bolle in pentola. Se i rappresentanti dei giornalisti pensionati non saranno consultati adesso e subito sulle effettive difficolt? economiche e finanziarie e sulle misure da prendere, ma messi di fronte al fatto compiuto dei tagli alle pensioni, la reazione dovr? essere durissima persino nei confronti del sindacato (l\u2019altra faccia della medaglia dell\u2019Inpgi) che ha l\u2019obbligo di tutelare tutti alla pari e ascoltare le ragioni di tutti, non soltanto dei colleghi in attivit?. Per i loro legami con l\u2019Istituto, i pensionati si reputano tra gli interlocutori principali nella causa comune per la salvezza dell\u2019Istituto, per la tenuta dei bilanci e per la salvaguardia delle garanzie istituzionali. Ignorarli significa alimentare il clima di giustizialismo che li colpisce nel Paese, complice la casta politica in cerca di alibi sul dissesto delle casse pubbliche. La stretta ventilata, specie se dolorosa e senza precedenti, non ? una variabile amministrativa di routine, ma una scelta politica che richiede il consenso e il contributo dei diretti interessati altrimenti si pecca di scorrettezza e si incorre, come gi? successo, nei rischi dei ricorsi ai tribunali deputati. Proprio nei giorni scorsi, l\u2019Inpgi si ? dato finalmente un Codice etico e un regolamento sulla trasparenza nella gestione degli atti amministrativi, nell\u2019azione della governance, nella disciplina interna, e ci? in sintonia con la legge sulla pubblica amministrazione. Speriamo che sia la volta buona per rispettare il diritto dei soci a sapere, a conoscere ogni piega dell\u2019attivit? dell\u2019Istituto in corso d\u2019opera, specie se comporta una manovra straordinaria per la riduzione dei redditi previdenziali, per gli aumenti contributivi, stavolta anche per i colleghi con contratto, e per la contrazione delle prestazioni assistenziali, senza contare le ombre ancora da diradare sul caso Sopaf. Ormai non ? pi? un mistero, nonostante ci si culli sui bilanci attivi, che la forbice fra entrate contributive e le uscite previdenziali e assistenziali si stia allargando in forme vertiginose (123% nel 2013, 130% nel 2014, e oltre 100 milioni quest\u2019anno). Con il crollo delle contribuzioni e con l\u2019esplosione dei costi dei prepensionamenti e degli ammortizzatori sociali (36,2 milioni + 8,1% rispetto 2013 per coprire, fra l\u2019altro, 2.858 contratti di solidariet? in atto persino nei grandi giornali), le riserve e le rendite del patrimonio immobiliare, peraltro destinato ad essere ridimensionati per legge, non basteranno pi? a coprire il deficit. Al di l? del rigoroso rispetto dei compiti istituzionali, il rapporto della solidariet? tra colleghi e tra generazioni ha distinto l\u2019Inpgi fin dalla nascita ed ? una caratteristica della sua autonomia. A prescindere da ogni ragionevole obiezione, avvilisce che continui il giro di vite sulle prestazioni previste dall\u2019art. 3 dello Statuto (dopo il blocco dei mutui e la riduzione dei prestiti, sarebbero in predicato le case di riposo per i nostri vecchi soli e con pensioni di fame). L\u2019Ungp e i gruppi territoriali costituiscono da sempre un organismo sindacale di base e, come l\u2019Usigrai, sono una costola imprescindibile della Fnsi. Partecipano alle trattative con gli editori e sottoscrivono il contratto dei giornalisti nell\u2019interesse di tutti i sindacalizzati, vuoi in attivit? vuoi in quiescenza. I suoi esponenti, perci?, hanno diritto di avere voce in capitolo nella definizione della ventilata operazione economica-finanziaria di risparmi e sacrifici in preparazione all\u2019Inpgi.. Sarebbero un affronto e una discriminazioni inaccettabili, se, nel momento di chiedere lacrime e sangue, si ignorassero la voce, le preoccupazioni, i suggerimenti e le controproposte dei giornalisti pensionati. Quando si invoca anche in casa nostra il patto generazionale gli occhi puntano sul pensionato pi? facile da individuare e da colpire. Differentemente dal fisco che non fa sconti a nessuno e non fa differenza tra cittadini in attivit? o in quiescenza. I giornalisti pensionati pagano gi? un prezzo salato alla crisi nel nome della solidariet?: blocco delle perequazioni e tagli in base alla legge 147\/2013 (le pensioni pi? alte); il raggiro beffa della sentenza della Consulta sulla restituzione delle indicizzazioni 2012\/2013 cancellate dalla Fornero; il monte delle pensioni di oggi e di domani eroso dagli ammortizzatori sociali, diversamente dalle altre categorie dei lavoratori a totale carico della fiscalit? generale; lo scandaloso sperpero dei contributi figurativi e delle pensioni\/vitalizi regalati alla casta. Siamo consapevoli che, avanti di questo passo, i giornalisti di oggi (15mila colleghi a contratto spesso depotenziato e con il posto a rischio contro 60mila precari, sfruttati e sottopagati) vadano incontro a un futuro di quattro soldi di pensione. Di fronte al declino del mercato editoriale e al crollo dell\u2019occupazione (mille disoccupati solo nel 2014), non si pu? restare con le mani in mano. Il sindacato dei giornalisti non pu? continuare a rinserrare i ranghi, ignorando la maggioranza dei lavoratori in cerca di solidariet? e di tutele sindacali. I nostri dirimpettai, governo (troppe vane promesse) ed editori miopi e tagliatori di teste continueranno ad inchiodarci all\u2019angolo fintanto che non saranno sindacalizzati, con certezze di diritti e di doveri, quanti sono oggi quelli che svolgono lo stesso mestiere, restituendo forza ed autorevolezza alle nostre organizzazioni. Per ora segnali in questa direzione provengono soltanto dall\u2019Associazione stampa romana. E poi non possiamo abbandonare nelle secche dell\u2019 immobilismo il Fondo pensione integrativa, ridotto ad etichetta e a bancomat per i colleghi in difficolt?. Sulla scia delle forme assicurative Aspi adesso diventato Naspi promosse dall\u2019Inps, si potrebbe costituire un pilastro assicurativo, d\u2019intesa fra le parti sociali, allo scopo di stornare dal costo delle pensioni il peso sempre pi? insopportabile delle spese per gli ammortizzatori sociali. Da condividere, infine, le idee e le proposte del Gruppo lombardo giornalisti pensionati a proposito dell\u2019opportunit? di una \u201cnuova Inpgi\u201d per recuperare l\u2019identit? perduta, ricordando che l\u2019istituto \u201c? nato per garantire e tutelare gli interessi previdenziali dei giornalisti mentre nel tempo ? stato coinvolto in trattative anche contrattuali che hanno comportato oneri estranei alla gestione previdenziali e a favore, per esempio, degli editori\u201d. I colleghi lombardi invocano la spendig review, proponendo, fra l\u2019altro, di eliminare il pletorico consiglio generale con lo scopo di azzerare i costi di un organo inutile e di riportare la nomina del consiglio di amministrazione all\u2019elezione diretta da parte dei giornalisti. Post scriptum ? Nella giornata nazionale della previdenza tenutasi il 13 maggio a Napoli, il presidente dell\u2019Inpgi, Andrea Camporese, ha fornito i seguenti dati. 14.688 giornalisti hanno contratto a tempo indeterminato, mentre 1.203 hanno un rapporto lavorativo a termine a fronte di quasi \u201c60mila operanti a vario titolo nel settore\u201d. Il trend di assunzioni e cessazioni vede 1.706 ingressi nel 2014 a fronte di 2.641 interruzioni con un saldo negativo di 935 unit?. Nello scorso anno, l\u2019Inpgi ha erogato 2.013 trattamenti di disoccupazione, 772 di cassa integrazione straordinari, e ben 2.858 contributi per contratti di solidariet?. Per il governo non sarebbe giusto rimborsare, come richiesto dalla Consulta, tutti i pensionati che hanno subito il blocco della perequazione. Mentre sarebbe giusto continuare a sperperare la spesa pubblica cresciuta di 107, 2 miliardi (dati di Sergio Rizzo sul Corriere della Sera del18\/5\/15) da quando si ? cominciato a promettere la stretta della spending review. Pertanto, il maltolto non sar? restituito persino alle presunte \u201cpensioni d\u2019oro\u201d di 1.500\/600 euro nette al mese, mentre a quelli ammessi per grazia ricevuta, si promette il rimborso\/elemosina dal 10% al 40% del dovuto. Naturalmente si pagheranno le tasse fino all\u2019ultima euro. I pensionati italiani pagano di tasse 66 miliardi di euro all\u2019anno, bench\u00e9 ingiuste ed illegittime, e che andrebbero messe nel conto per la quadratura in attivo del sistema previdenziale. L\u2019Italia ? l\u2019unico Paese al mondo che non offre ai pensionati n\u00e9 sconti sul fisco, n\u00e9 altri benefici mirati di carattere sociale. I pensionati sono veri e propri ammortizzatori sociali, nonni bancomat per le loro famiglie. Contribuiscono con 6 miliardi di euro l\u2019anno per mantenere figli e nipoti. Le famiglie risparmiano 24 miliardi di euro l\u2019anno grazie all\u2019aiuto dei nonni baby-sitter. (20\/5\/2015)<\/p>\n<p>RB<\/p>\n<p>28\/05\/15<\/p>\n","protected":false},"excerpt":{"rendered":"<p>di Romano Bartoloni (segretario del SCR e presidente del Gruppo romano giornalisti pensionati) Anche se all\u2019Inpgi restano abbottonati contro ogni buona regola di trasparenza, di rispetto dei diritti\/doveri dei soci e di coinvolgimento e corresponsabilit? dell\u2019intera categoria (nell\u2019Inpgi1 15mila i contrattualizzati a tempo indeterminato e 8mila i pensionati), sembra che si profilino inevitabili sacrifici per [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-593","post","type-post","status-publish","format-standard","hentry","category-archivioarticoliprecedenti"],"_links":{"self":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/comments?post=593"}],"version-history":[{"count":2,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/593\/revisions"}],"predecessor-version":[{"id":622,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/593\/revisions\/622"}],"wp:attachment":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/media?parent=593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/categories?post=593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/tags?post=593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}