{"id":581,"date":"2015-08-24T18:05:29","date_gmt":"2015-08-24T16:05:29","guid":{"rendered":"https:\/\/www.sindacatocronisti.it\/wordpress\/2020\/08\/24\/mafia-e-minacce-federica-angeli-premiata-da-articolo-21-2\/"},"modified":"2020-08-24T22:55:56","modified_gmt":"2020-08-24T20:55:56","slug":"mafia-e-minacce-federica-angeli-premiata-da-articolo-21-2","status":"publish","type":"post","link":"https:\/\/www.sindacatocronisti.it\/wordpress\/2015\/08\/24\/mafia-e-minacce-federica-angeli-premiata-da-articolo-21-2\/","title":{"rendered":"Mafia e minacce: Federica Angeli premiata da Articolo 21"},"content":{"rendered":"<div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Read Time:<\/span>32 Second                <\/div>\n\n            <\/div><p>La collega Federica Angeli di Repubblica, sotto scorta per le sue inchieste sulla mafia ad Ostia, ? stata premiata gioved? 28 maggio in occasione della festa di \u201cArticolo 21\u201d , associazione che da tempo ? impegnata in battaglie per la libert? di stampa che sono condivise dal Sindacato cronisti romani. Articolo 21 ? un\u2019associazione di giornalisti, giuristi ed esponenti del mondo della cultura che si propone di promuovere il principio della libert? di manifestazione del pensiero. Federica Angeli ? anche impegnata con il Sindacato cronisti romani (? componente del Direttivo) e componente di Giunta dell\u2019Unci. Con Federica sono stati premiati altri tre colleghi: Sandro Ruotolo, Chiara Cazzaniga, Enzo Palmesano.<\/p>\n<p>SCR<\/p>\n<p>29\/05\/15<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La collega Federica Angeli di Repubblica, sotto scorta per le sue inchieste sulla mafia ad Ostia, ? stata premiata gioved? 28 maggio in occasione della festa di \u201cArticolo 21\u201d , associazione che da tempo ? impegnata in battaglie per la libert? di stampa che sono condivise dal Sindacato cronisti romani. Articolo 21 ? un\u2019associazione di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-581","post","type-post","status-publish","format-standard","hentry","category-archivioarticoliprecedenti"],"_links":{"self":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/comments?post=581"}],"version-history":[{"count":1,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/581\/revisions"}],"predecessor-version":[{"id":633,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/581\/revisions\/633"}],"wp:attachment":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/media?parent=581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/categories?post=581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/tags?post=581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}