{"id":1070,"date":"2015-08-20T14:58:00","date_gmt":"2015-08-20T12:58:00","guid":{"rendered":"https:\/\/www.sindacatocronisti.it\/wordpress\/?p=1070"},"modified":"2020-08-31T15:00:49","modified_gmt":"2020-08-31T13:00:49","slug":"black-bloc-vergognose-le-frasi-di-foschi","status":"publish","type":"post","link":"https:\/\/www.sindacatocronisti.it\/wordpress\/2015\/08\/20\/black-bloc-vergognose-le-frasi-di-foschi\/","title":{"rendered":"Black Bloc, vergognose le frasi di Foschi"},"content":{"rendered":"<div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Read Time:<\/span>42 Second                <\/div>\n\n            <\/div>\n<p>Il Sindacato cronisti romani vicino ai tanti colleghi che hanno seguito con scrupolo professionale e a rischio della propria incolumit\u00e0 le due giorni di pesanti manifestazioni nel cuore della citt\u00e0 . Esprime fraterna solidariet\u00e0 ai cronisti e ai fotografi aggrediti nel compiere il loro dovere.  <\/p>\n\n\n\n<p>Il SCR \u00e8 sorpreso e amareggiato per le vergognose dichiarazioni fatte via Facebook del capo della segreteria del Sindaco di Roma, Enzo Foschi, nell&#8217;affermare irresponsabilmente che &#8220;i veri black bloc sono tutti quei giornalisti infiltrati nel corteo, delusi dal fatto che non scorra sangue&#8221;. <\/p>\n\n\n\n<p>Piuttosto la vera delusione l&#8217;ha data il sindaco Marino in quei critici momenti in visita a Cracovia. Pur distante per ragioni onorevoli, pur seguendo da lontano gli eventi, di fatto ha lasciato i suoi concittadini in balia delle tensioni, dei disordini e dei disagi in una citt\u00e0 in stato d&#8217;assedio con l&#8217;allarme rosso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Sindacato cronisti romani vicino ai tanti colleghi che hanno seguito con scrupolo professionale e a rischio della propria incolumit\u00e0 le due giorni di pesanti manifestazioni nel cuore della citt\u00e0 . Esprime fraterna solidariet\u00e0 ai cronisti e ai fotografi aggrediti nel compiere il loro dovere. Il SCR \u00e8 sorpreso e amareggiato per le vergognose dichiarazioni [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1070","post","type-post","status-publish","format-standard","hentry","category-archivioarticoliprecedenti"],"_links":{"self":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/1070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/comments?post=1070"}],"version-history":[{"count":2,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/1070\/revisions"}],"predecessor-version":[{"id":1072,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/1070\/revisions\/1072"}],"wp:attachment":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/media?parent=1070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/categories?post=1070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/tags?post=1070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}