{"id":106,"date":"2015-05-23T00:00:00","date_gmt":"2015-05-22T22:00:00","guid":{"rendered":"https:\/\/www.sindacatocronisti.it\/wordpress\/2015\/05\/23\/intimidazioni-ai-giornalisti\/"},"modified":"2015-05-23T00:00:00","modified_gmt":"2015-05-22T22:00:00","slug":"intimidazioni-ai-giornalisti","status":"publish","type":"post","link":"https:\/\/www.sindacatocronisti.it\/wordpress\/2015\/05\/23\/intimidazioni-ai-giornalisti\/","title":{"rendered":"Intimidazioni ai giornalisti. Tutela speciale nel contratto per i non garantiti"},"content":{"rendered":"<div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Read Time:<\/span>1 Minute, 4 Second                <\/div>\n\n            <\/div><p><em>L&#8217;ultimo episodio nelle Marche: in fiamme auto e motorino di un cronista<\/em><\/p>\n<p> Un fondo di tutela per i giornalisti non garantiti da un contratto Fieg-Fnsi che li tuteli economicamente da tutti gli atti di aggressione, economica e giudiziaria, a cui il loro lavoro li espone. \u00e8 una delle proposte che il Sindacato cronisti romani intende fare alla Fnsi in vista del confronto che andr\u00e0 ad aprirsi nei prossimi mesi per il rinnovo del Contratto nazionale dei giornalisti. Lo spunto della proposta del Sindacato cronisti romani nasce dall\u2019ennesimo episodio di intimidazione che ha come bersaglio un giornalista, e soprattutto un giornalista non garantito da un rapporto \u201carticolo 1\u201d del contratto nazionale di lavoro. La notte scorsa uno o pi\u00f9 sconosciuti hanno dato alle fiamme l\u2019auto e il motorino del collega Aurelio Bufalari, che cura le corrispondenze da Porto Recanati dello storico quotidiano delle Marche, il Corriere Adriatico. Sia Bufalari che i suoi colleghi della zona sono stati recentemente minacciati. Non c\u2019\u00e8 nessun dubbio che l\u2019incendio fosse doloso (\u00e8 stata anche rinvenuta una tanica di liquido infiammabile) e non c\u2019\u00e8 nessun dubbio che il bersaglio dell\u2019intimidazione fosse Bufalari, perch\u00e9 l\u2019auto e la moto non erano parcheggiati vicini e sono stati gli unici veicoli colpiti nella zona.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ultimo episodio nelle Marche: in fiamme auto e motorino di un cronista Un fondo di tutela per i giornalisti non garantiti da un contratto Fieg-Fnsi che li tuteli economicamente da tutti gli atti di aggressione, economica e giudiziaria, a cui il loro lavoro li espone. \u00e8 una delle proposte che il Sindacato cronisti romani intende [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-106","post","type-post","status-publish","format-standard","hentry","category-archivioarticoliprecedenti"],"_links":{"self":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/comments?post=106"}],"version-history":[{"count":0,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/106\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/media?parent=106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/categories?post=106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/tags?post=106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}