{"id":102,"date":"2015-05-13T00:00:00","date_gmt":"2015-05-12T22:00:00","guid":{"rendered":"https:\/\/www.sindacatocronisti.it\/wordpress\/2015\/05\/13\/al-tavolo-dell-editoria-il-governo-cambia-prassi\/"},"modified":"2015-05-13T00:00:00","modified_gmt":"2015-05-12T22:00:00","slug":"al-tavolo-dell-editoria-il-governo-cambia-prassi","status":"publish","type":"post","link":"https:\/\/www.sindacatocronisti.it\/wordpress\/2015\/05\/13\/al-tavolo-dell-editoria-il-governo-cambia-prassi\/","title":{"rendered":"Al tavolo dell&#8217;Editoria il governo &#8220;cambia prassi&#8221;"},"content":{"rendered":"<div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Read Time:<\/span>28 Second                <\/div>\n\n            <\/div><p>Il tanto atteso tavolo sull&#8217;Editoria, dopo tanti rinvii, si \u00e8 finalmente tenuto alle 15 di marted\u00ec 12 maggio. Convocate una trentina di associazioni, dagli edicolanti ai distributori alla Fieg e alla Fnsi, si \u00e8 risolto per ora con un nulla di fatto. Il sottosegretario alla Presidenza del Consiglio Luca Lotti ha aggiornato la riunione, dopo che avevano parlato tutti gli &#8220;attori in campo&#8221;, a una prossima convocazione ancora da stabilire. La nota di colore della riunione \u00e8 stata proprio una battuta di Lotti: &#8220;Contrariamente alla prassi di questo Governo, ascolter\u00e0 prima di decidere&#8221;.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il tanto atteso tavolo sull&#8217;Editoria, dopo tanti rinvii, si \u00e8 finalmente tenuto alle 15 di marted\u00ec 12 maggio. Convocate una trentina di associazioni, dagli edicolanti ai distributori alla Fieg e alla Fnsi, si \u00e8 risolto per ora con un nulla di fatto. Il sottosegretario alla Presidenza del Consiglio Luca Lotti ha aggiornato la riunione, dopo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-102","post","type-post","status-publish","format-standard","hentry","category-archivioarticoliprecedenti"],"_links":{"self":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/comments?post=102"}],"version-history":[{"count":0,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/posts\/102\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/media?parent=102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/categories?post=102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindacatocronisti.it\/wordpress\/wp-json\/wp\/v2\/tags?post=102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}